{"id":10,"date":"2021-02-23T16:49:02","date_gmt":"2021-02-23T19:49:02","guid":{"rendered":"https:\/\/cotran.com.br\/inspecaoveicular\/?page_id=10"},"modified":"2023-01-24T11:55:04","modified_gmt":"2023-01-24T14:55:04","slug":"inspecao-kit-gas","status":"publish","type":"page","link":"https:\/\/cotran.com.br\/inspecaoveicular\/inspecao-kit-gas\/","title":{"rendered":"Inspe\u00e7\u00e3o Kit GNV"},"content":{"rendered":"<div class=\"su-note\"  style=\"border-color:#dddddd;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#f7f7f7;border-color:#ffffff;color:#333333;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\">\n<p><strong>A COTRAN \u00e9 a N\u00ba 1 em servi\u00e7os de inspe\u00e7\u00e3o de kit GNV na Baixada Fluminense, com servi\u00e7os acreditados pela\u00a0 Coordena\u00e7\u00e3o Geral de Acredita\u00e7\u00e3o do INMETRO e DENATRAN.<\/strong><\/p>\n<p>Oferecemos as melhores condi\u00e7\u00f5es para em <strong>inspe\u00e7\u00e3o de Kit GNV<\/strong>,\u00a0 atendendo especialmente a motoristas profissionais &#8211;\u00a0 t\u00e1xi, Uber, 99 e demais aplicativos &#8211; al\u00e9m de caminhoneiros e frotas, Fazemos a sua inspe\u00e7\u00e3o anual obrigat\u00f3ria de\u00a0 sistema GNV ve\u00edcular, atendendo aos requisitos dos \u00f3rg\u00e3os de tr\u00e2nsito.<\/p>\n<p><strong>Ligue e agende sua inspe\u00e7\u00e3o GNV com a COTRAN: o menor pre\u00e7o em Caxias e Baixada Fluminense!<\/strong><\/p>\n<\/div><\/div>\n<div class=\"su-image-carousel  su-image-carousel-columns-3 su-image-carousel-has-spacing su-image-carousel-crop su-image-carousel-crop-4-3 su-image-carousel-has-lightbox su-image-carousel-has-outline su-image-carousel-adaptive su-image-carousel-slides-style-default su-image-carousel-controls-style-dark su-image-carousel-align-none\" style=\"\" data-flickity-options='{\"groupCells\":true,\"cellSelector\":\".su-image-carousel-item\",\"adaptiveHeight\":false,\"cellAlign\":\"left\",\"prevNextButtons\":true,\"pageDots\":true,\"autoPlay\":5000,\"imagesLoaded\":true,\"contain\":true,\"selectedAttraction\":0.025000000000000001387778780781445675529539585113525390625,\"friction\":0.2800000000000000266453525910037569701671600341796875}' id=\"su_image_carousel_6a97cc70bf287\"><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/video1.png\" target=\"_blank\" rel=\"noopener noreferrer\" data-caption=\"COTRAN - Controle de Transportes\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"464\" src=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/video1.png\" class=\"\" alt=\"Cotran - Controle de Transportes Ltda\" srcset=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/video1.png 571w, https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/video1-300x244.png 300w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/007.jpg\" target=\"_blank\" rel=\"noopener noreferrer\" data-caption=\"COTRAN - Controle de Transportes\" data-rel=\"lightbox-image-1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/007.jpg\" class=\"\" alt=\"COTRAN-Controle de Transportes\" srcset=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/007.jpg 960w, https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/007-300x225.jpg 300w, https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/007-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/006.jpg\" target=\"_blank\" rel=\"noopener noreferrer\" data-caption=\"COTRAN - Controle de Transportes\" data-rel=\"lightbox-image-2\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/006.jpg\" class=\"\" alt=\"COTRAN - Controle de Transportes\" srcset=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/006.jpg 960w, https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/006-300x225.jpg 300w, https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/006-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/005.jpg\" target=\"_blank\" rel=\"noopener noreferrer\" data-caption=\"COTRAN - Controle de Transportes\" data-rel=\"lightbox-image-3\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/005.jpg\" class=\"\" alt=\"COTRAN-Controle de Transportes\" srcset=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/005.jpg 960w, https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/005-300x225.jpg 300w, https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/005-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/004.jpg\" target=\"_blank\" rel=\"noopener noreferrer\" data-caption=\"COTRAN - Controle de Transportes\" data-rel=\"lightbox-image-4\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/004.jpg\" class=\"\" alt=\"COTRAN-Controle de Transportes\" srcset=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/004.jpg 960w, https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/004-300x225.jpg 300w, https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/004-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/003.jpg\" target=\"_blank\" rel=\"noopener noreferrer\" data-caption=\"COTRAN - Controle de Transportes\" data-rel=\"lightbox-image-5\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/003.jpg\" class=\"\" alt=\"COTRAN-Controle de Transportes\" srcset=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/003.jpg 960w, https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/003-300x225.jpg 300w, https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/003-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/002.jpg\" target=\"_blank\" rel=\"noopener noreferrer\" data-caption=\"COTRAN - Controle de Transportes\" data-rel=\"lightbox-image-6\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/002.jpg\" class=\"\" alt=\"COTRAN-Vistoria Veicular\" srcset=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/002.jpg 960w, https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/002-300x225.jpg 300w, https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/002-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/001-1.jpg\" target=\"_blank\" rel=\"noopener noreferrer\" data-caption=\"COTRAN - Controle de Transportes\" data-rel=\"lightbox-image-7\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"709\" height=\"800\" src=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/001-1.jpg\" class=\"\" alt=\"COTRAN-Vistoria Veicular\" srcset=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/001-1.jpg 709w, https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/001-1-266x300.jpg 266w\" sizes=\"auto, (max-width: 709px) 100vw, 709px\" \/><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/001.jpg\" target=\"_blank\" rel=\"noopener noreferrer\" data-caption=\"COTRAN - Controle de Transportes\" data-rel=\"lightbox-image-8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/001.jpg\" class=\"\" alt=\"COTRAN Vistoria Veicular\" srcset=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/001.jpg 960w, https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/001-300x225.jpg 300w, https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2021\/03\/001-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/div><\/div><\/div><script id=\"su_image_carousel_6a97cc70bf287_script\">if(window.SUImageCarousel){setTimeout(function() {window.SUImageCarousel.initGallery(document.getElementById(\"su_image_carousel_6a97cc70bf287\"))}, 0);}var su_image_carousel_6a97cc70bf287_script=document.getElementById(\"su_image_carousel_6a97cc70bf287_script\");if(su_image_carousel_6a97cc70bf287_script){su_image_carousel_6a97cc70bf287_script.parentNode.removeChild(su_image_carousel_6a97cc70bf287_script);}<\/script>\n<h2><strong>O QUE VOC\u00ca PRECISA SABER SOBRE GNV<\/strong><\/h2>\n<p>Clique nos t\u00f3picos abaixo e saiba mais sobre vistoria GNV:<\/p>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>QUAIS S\u00c3O OS DOCUMENTOS NECESS\u00c1RIOS?<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Documentos necess\u00e1rios para a 1\u00aa vistoria do ve\u00edculo convertido ao GNV s\u00e3o:<br \/>\n\u2013 Autoriza\u00e7\u00e3o pr\u00e9via do Detran, solicitada pelo tele-atendimento 3460-4040 op\u00e7\u00e3o 7;<br \/>\n\u2013 Documento do ve\u00edculo (CRLV) (nos casos de ve\u00edculos 0KM dever\u00e1 ser apresentada a Nota fiscal de compra);<br \/>\n\u2013 Atestado de Qualidade da empresa instaladora, comprovando o registro acreditada pela Coordena\u00e7\u00e3o Geral de Acredita\u00e7\u00e3o do INMETRO;<br \/>\n\u2013 CNH do condutor;<br \/>\n\u2013 Certificado de Conformidade\u201d do cilindro;<br \/>\n\u2013 Nota Fiscal do servi\u00e7o de instala\u00e7\u00e3o executado no veiculo;<br \/>\n\u2013 Nota Fiscal de compra dos componentes do sistema GNV.<\/p>\n<a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/contato\/\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#15459A;border-color:#11387c;border-radius:6px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#5c7db9;border-radius:6px;text-shadow:none\"><i class=\"sui sui-headphones\" style=\"font-size:14px;color:#FFFFFF\"><\/i> FALE CONOSCO<\/span><\/a> <a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/tabela-precos\/\" class=\"su-button su-button-style-default\" style=\"color:#000000;background-color:#FFBA00;border-color:#cc9500;border-radius:6px\" target=\"_self\"><span style=\"color:#000000;padding:6px 18px;font-size:14px;line-height:21px;border-color:#ffcf4d;border-radius:6px;text-shadow:none\"><i class=\"sui sui-search-plus\" style=\"font-size:14px;color:#FFFFFF\"><\/i> VER PRE\u00c7OS<\/span><\/a>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>A VISTORIA \u00c9 OBRIGAT\u00d3RIO AO LICENCIAMENTO ANUAL?<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Sim. Ao transitar com o ve\u00edculo portando a documenta\u00e7\u00e3o do GNV com validade vencida, o propriet\u00e1rio poder\u00e1 ter o licenciamento anual do seu carro negado pelo DETRAN e ter o ve\u00edculo apreendido pela autoridade de tr\u00e2nsito.<br \/>\nA inspe\u00e7\u00e3o do veiculo convertido ao uso de gnv deve ser renovada todos os anos na data descrita no verso do selo.<\/p>\n<a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/contato\/\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#15459A;border-color:#11387c;border-radius:6px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#5c7db9;border-radius:6px;text-shadow:none\"><i class=\"sui sui-headphones\" style=\"font-size:14px;color:#FFFFFF\"><\/i> FALE CONOSCO<\/span><\/a> <a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/tabela-precos\/\" class=\"su-button su-button-style-default\" style=\"color:#000000;background-color:#FFBA00;border-color:#cc9500;border-radius:6px\" target=\"_self\"><span style=\"color:#000000;padding:6px 18px;font-size:14px;line-height:21px;border-color:#ffcf4d;border-radius:6px;text-shadow:none\"><i class=\"sui sui-search-plus\" style=\"font-size:14px;color:#FFFFFF\"><\/i> VER PRE\u00c7OS<\/span><\/a>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>O QUE \u00c9 PRECISO SABER ANTES DE CONVERTER PARA GNV?<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p><strong>Antes de converter seu ve\u00edculo, considere:<\/strong><br \/>\n\u2013 Antes de se decidir sobre a convers\u00e3o do seu ve\u00edculo, pesquise as diferentes op\u00e7\u00f5es de kits de convers\u00e3o (cilindro e redutor) e de empresas registradas na sua cidade ou regi\u00e3o.<br \/>\n\u2013 Visite a empresa e pe\u00e7a informa\u00e7\u00f5es para o respons\u00e1vel t\u00e9cnico quanto aos aspectos de seguran\u00e7a, desempenho, adequa\u00e7\u00e3o ao seu modelo de ve\u00edculo e consumo relativos ao kit comercializado pela empresa.<br \/>\n\u2013 A grande perda de pot\u00eancia, um mito antigo nas instala\u00e7\u00f5es dos sistemas de GNV, hoje encontra-se superado, existe tecnologia que acarreta uma perda na ordem de 2 a 3% da pot\u00eancia do ve\u00edculo.<br \/>\n\u2013 Lembre-se: exija sempre a Nota Fiscal do servi\u00e7o de convers\u00e3o e dos componentes instalados no seu ve\u00edculo. No corpo da Nota Fiscal dever\u00e1 constar os n\u00fameros dos principais componentes dos Kits (cilindro e redutor).<\/p>\n<a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/contato\/\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#15459A;border-color:#11387c;border-radius:6px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#5c7db9;border-radius:6px;text-shadow:none\"><i class=\"sui sui-headphones\" style=\"font-size:14px;color:#FFFFFF\"><\/i> FALE CONOSCO<\/span><\/a> <a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/tabela-precos\/\" class=\"su-button su-button-style-default\" style=\"color:#000000;background-color:#FFBA00;border-color:#cc9500;border-radius:6px\" target=\"_self\"><span style=\"color:#000000;padding:6px 18px;font-size:14px;line-height:21px;border-color:#ffcf4d;border-radius:6px;text-shadow:none\"><i class=\"sui sui-search-plus\" style=\"font-size:14px;color:#FFFFFF\"><\/i> VER PRE\u00c7OS<\/span><\/a>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>DOCUMENTOS NECESS\u00c1RIOS PARA INSPE\u00c7\u00c3O INICIAL, APOS A CONVERS\u00c3O GNV:<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\nCRLV;<br \/>\nCNH condutor;<br \/>\nCertificado de conformidade do cilindro;<br \/>\nAtestado de qualidade do convertedor homologado;<br \/>\nNotas fiscais de instala\u00e7\u00e3o e venda do Kit-GNV<br \/>\nAutoriza\u00e7\u00e3o pr\u00e9via DETRAN RJ: (21) 3460-4041 ou (21) 3460-4040<\/p>\n<a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/contato\/\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#15459A;border-color:#11387c;border-radius:6px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#5c7db9;border-radius:6px;text-shadow:none\"><i class=\"sui sui-headphones\" style=\"font-size:14px;color:#FFFFFF\"><\/i> FALE CONOSCO<\/span><\/a> <a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/tabela-precos\/\" class=\"su-button su-button-style-default\" style=\"color:#000000;background-color:#FFBA00;border-color:#cc9500;border-radius:6px\" target=\"_self\"><span style=\"color:#000000;padding:6px 18px;font-size:14px;line-height:21px;border-color:#ffcf4d;border-radius:6px;text-shadow:none\"><i class=\"sui sui-search-plus\" style=\"font-size:14px;color:#FFFFFF\"><\/i> VER PRE\u00c7OS<\/span><\/a>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>DOCUMENTOS NECESS\u00c1RIOS PARA INSPE\u00c7\u00c3O NA RENOVA\u00c7\u00c3O:<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>CRLV;<br \/>\nCNH condutor;<br \/>\nSelo g\u00e1s natural vigente.<\/p>\n<p>Ao transitar com o ve\u00edculo portando a documenta\u00e7\u00e3o do GNV com validade vencida, o propriet\u00e1rio poder\u00e1 ter o licenciamento anual do seu carro negado pelo DETRAN e ter o ve\u00edculo apreendido pela autoridade de tr\u00e2nsito.<\/p>\n<p>N\u00e3o \u00e9 permitido a instala\u00e7\u00e3o de gnv em sistema turbo-alimentados adaptados. com exce\u00e7\u00e3o para os ve\u00edculo sobrealimentados de f\u00e1brica. Resolu\u00e7\u00e3o do CONAMA<\/p>\n<p>Todo cilindro de GNV deve ser requalificado (testado) a cada 5 anos.<\/p>\n<a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/contato\/\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#15459A;border-color:#11387c;border-radius:6px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#5c7db9;border-radius:6px;text-shadow:none\"><i class=\"sui sui-headphones\" style=\"font-size:14px;color:#FFFFFF\"><\/i> FALE CONOSCO<\/span><\/a> <a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/tabela-precos\/\" class=\"su-button su-button-style-default\" style=\"color:#000000;background-color:#FFBA00;border-color:#cc9500;border-radius:6px\" target=\"_self\"><span style=\"color:#000000;padding:6px 18px;font-size:14px;line-height:21px;border-color:#ffcf4d;border-radius:6px;text-shadow:none\"><i class=\"sui sui-search-plus\" style=\"font-size:14px;color:#FFFFFF\"><\/i> VER PRE\u00c7OS<\/span><\/a>\n<\/div><\/div>\n<a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/tabela-precos\/\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#15459A;border-color:#11387c;border-radius:6px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#5c7db9;border-radius:6px;text-shadow:none\"><i class=\"sui sui-headphones\" style=\"font-size:14px;color:#FFFFFF\"><\/i> PRE\u00c7OS<\/span><\/a> <a href=\"https:\/\/www.instagram.com\/cotran_vistoria\/\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#FFBA00;border-color:#cc9500;border-radius:6px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#ffcf4d;border-radius:6px;text-shadow:none\"><i class=\"sui sui-search-plus\" style=\"font-size:14px;color:#FFFFFF\"><\/i> INSTAGRAM<\/span><\/a> <a href=\"https:\/\/web.whatsapp.com\/send?phone=5521986698115\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#2D89EF;border-color:#246ec0;border-radius:5px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:6px 16px;font-size:13px;line-height:20px;border-color:#6cadf4;border-radius:5px;text-shadow:none\"><i class=\"sui sui-search-plus\" style=\"font-size:13px;color:#FFFFFF\"><\/i> WHATSAPP<\/span><\/a>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/cotran.com.br\/inspecaoveicular\/contato\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-292 size-full\" src=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2023\/01\/banner00.jpg\" alt=\"\" width=\"800\" height=\"275\" srcset=\"https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2023\/01\/banner00.jpg 800w, https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2023\/01\/banner00-300x103.jpg 300w, https:\/\/cotran.com.br\/inspecaoveicular\/wp-content\/uploads\/2023\/01\/banner00-768x264.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O QUE VOC\u00ca PRECISA SABER SOBRE GNV Clique nos t\u00f3picos abaixo e saiba mais sobre vistoria GNV: &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-10","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cotran.com.br\/inspecaoveicular\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cotran.com.br\/inspecaoveicular\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cotran.com.br\/inspecaoveicular\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cotran.com.br\/inspecaoveicular\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cotran.com.br\/inspecaoveicular\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":32,"href":"https:\/\/cotran.com.br\/inspecaoveicular\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"predecessor-version":[{"id":293,"href":"https:\/\/cotran.com.br\/inspecaoveicular\/wp-json\/wp\/v2\/pages\/10\/revisions\/293"}],"wp:attachment":[{"href":"https:\/\/cotran.com.br\/inspecaoveicular\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}